{"id":145,"date":"2026-05-13T15:14:31","date_gmt":"2026-05-13T13:14:31","guid":{"rendered":"https:\/\/metaesthetics.net\/suisse\/?page_id=145"},"modified":"2026-05-13T15:55:00","modified_gmt":"2026-05-13T13:55:00","slug":"bienne","status":"publish","type":"page","link":"https:\/\/metaesthetics.net\/suisse\/bienne\/","title":{"rendered":"Bienne"},"content":{"rendered":"\n<p>Bienvenue sur notre page d\u00e9di\u00e9e \u00e0 Bienne. D\u00e9couvrez l&#8217;ensemble des services de chirurgie et de m\u00e9decine esth\u00e9tique disponibles \u00e0 Bienne et dans sa r\u00e9gion. Parcourez les cat\u00e9gories ci-dessous pour explorer les traitements propos\u00e9s, comprendre leurs indications et leurs r\u00e9sultats, et trouver le praticien certifi\u00e9 qui vous accompagnera dans votre parcours.<\/p>\n\n\n\n<div class=\"wp-block-query is-layout-flow wp-block-query-is-layout-flow\"><ul class=\"wp-block-post-template is-layout-flow wp-block-post-template-is-layout-flow\"><li class=\"wp-block-post post-163 page type-page status-publish hentry\">\n<h2 class=\"wp-block-post-title\"><a href=\"https:\/\/metaesthetics.net\/suisse\/bienne\/medecine-esthetique\/\" target=\"_self\" >M\u00e9decine esth\u00e9tique<\/a><\/h2>\n\n<div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">La m\u00e9decine esth\u00e9tique \u00e0 Bienne regroupe l&#8217;ensemble des traitements non chirurgicaux destin\u00e9s \u00e0 corriger, harmoniser ou pr\u00e9venir les signes du vieillissement et les pr\u00e9occupations cutan\u00e9es. Parcourez ci-dessous les proc\u00e9dures propos\u00e9es par les praticiens certifi\u00e9s de la r\u00e9gion : indications, d\u00e9roulement, dur\u00e9e des r\u00e9sultats, risques et crit\u00e8res pour choisir le professionnel le mieux adapt\u00e9 \u00e0 votre&hellip; <\/p><\/div>\n<\/li><\/ul>\n\n\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bienvenue sur notre page d\u00e9di\u00e9e \u00e0 Bienne. D\u00e9couvrez l&#8217;ensemble des services de chirurgie et de m\u00e9decine esth\u00e9tique disponibles \u00e0 Bienne et dans sa r\u00e9gion. Parcourez les cat\u00e9gories ci-dessous pour explorer les traitements propos\u00e9s, comprendre leurs indications et leurs r\u00e9sultats, et trouver le praticien certifi\u00e9 qui vous accompagnera dans votre parcours.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-145","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/metaesthetics.net\/suisse\/wp-json\/wp\/v2\/pages\/145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metaesthetics.net\/suisse\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/metaesthetics.net\/suisse\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/metaesthetics.net\/suisse\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/metaesthetics.net\/suisse\/wp-json\/wp\/v2\/comments?post=145"}],"version-history":[{"count":4,"href":"https:\/\/metaesthetics.net\/suisse\/wp-json\/wp\/v2\/pages\/145\/revisions"}],"predecessor-version":[{"id":266,"href":"https:\/\/metaesthetics.net\/suisse\/wp-json\/wp\/v2\/pages\/145\/revisions\/266"}],"wp:attachment":[{"href":"https:\/\/metaesthetics.net\/suisse\/wp-json\/wp\/v2\/media?parent=145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}